{"id":3245,"date":"2021-10-04T14:05:00","date_gmt":"2021-10-04T12:05:00","guid":{"rendered":"http:\/\/www.clickclickdrive.de\/blog\/?p=3245"},"modified":"2022-02-18T16:50:28","modified_gmt":"2022-02-18T14:50:28","slug":"clickclickdrive-gmbh-entwicklungsjournal-september-2021","status":"publish","type":"post","link":"https:\/\/www.clickclickdrive.de\/blog\/clickclickdrive-gmbh-entwicklungsjournal-september-2021\/","title":{"rendered":"ClickClickDrive GmbH \u2013 Entwicklungsjournal September 2021"},"content":{"rendered":"\n<p>Was erwartet Sie diesen Monat neues bei ClickClickDrive? Das fassen wir Ihnen in dieser Mail einmal kurz und b\u00fcndig zusammen.<\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-96d8d27c-8bc2-451c-af1a-1a4c41e99be9\"><li>Zeitraum: September 2021<\/li><li>Produkt: Verwaltungssoftware<\/li><li>Bereich: Theorie<\/li><\/ul>\n\n\n\n<p>Zum Einen gibt es ein neue \u00fcberarbeitete Ansicht&nbsp;Ihrer f\u00fcr die Theorie-App registrierten Sch\u00fcler und Sch\u00fclerinnen:&nbsp;Dort k\u00f6nnen Sie&nbsp;nun einsehen&nbsp;wann Sie Ihre&nbsp;Sch\u00fcler\/ die Sch\u00fclerin registriert haben, wann der erste Login stattgefunden hat und wann Sie den Zugang zur Theorie-App verl\u00e4ngert haben.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns='http:\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20370%20247'%3E%3C\/svg%3E\" data-lazy-src=\"https:\/\/www.clickclickdrive.de\/blog\/wp-content\/uploads\/sites\/2\/2022\/01\/aad11c78-2b68-d68e-0ab3-c354eedf3963-2.gif\" alt=\"\" class=\"zeen-lazy-load-base zeen-lazy-load wp-image-3247\" \/><noscript><img decoding=\"async\" width=\"800\" height=\"360\" src=\"https:\/\/www.clickclickdrive.de\/blog\/wp-content\/uploads\/sites\/2\/2022\/01\/aad11c78-2b68-d68e-0ab3-c354eedf3963-2.gif\" alt=\"\" class=\"wp-image-3247\" \/><\/noscript><figcaption>Theorie \u00dcbersicht <br>Quelle: ClickClickDrive<\/figcaption><\/figure><\/div>\n\n\n\n<h4 class=\"has-text-align-center wp-block-heading\">Was gibt es sonst neues?<\/h4>\n\n\n\n<p>Abgesehen davon erwarten Sie noch weitere Erweiterungen&nbsp;in der Software.<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Wir haben noch weitere Tutorial Videos in der Verwaltungssoftware hinzugef\u00fcgt, die Ihnen immer wieder behilflich sein sollen.<\/li><li>Im Anmeldeformular steht nun neben dem Geburtsdatum, auch das Alter der Person.&nbsp;<\/li><li>Die Felder &#8222;Postleitzahl und Ort, Adresse, Land, Geburtsdatum, Staatsb\u00fcrgerschaft, Beruf, Brille, Behinderungen, Regierungsnummer, Geburtsort, Geburtsname&#8220; in der Sch\u00fcler Anmeldung sind nicht mehr in der Schaltfl\u00e4che &#8222;Mehr Anzeigen&#8220; versteckt.<\/li><li>In der \u00dcbersicht Ihrer Fahrsch\u00fcler\/-innen haben wir einen neuen Filter hinzugef\u00fcgt, welcher es Ihnen erm\u00f6glicht die Sch\u00fcler und Sch\u00fclerinnen nach Ihren Filialen zu filtern, in denen sie angemeldet sind.&nbsp;<\/li><\/ol>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"data:image\/svg+xml,%3Csvg%20xmlns='http:\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20370%20247'%3E%3C\/svg%3E\" data-lazy-src=\"https:\/\/www.clickclickdrive.de\/blog\/wp-content\/uploads\/sites\/2\/2022\/01\/7db11fdc-5f00-19c1-b433-c8d4af025179-1.gif\" alt=\"\" class=\"zeen-lazy-load-base zeen-lazy-load wp-image-3248\" \/><noscript><img decoding=\"async\" width=\"800\" height=\"360\" src=\"https:\/\/www.clickclickdrive.de\/blog\/wp-content\/uploads\/sites\/2\/2022\/01\/7db11fdc-5f00-19c1-b433-c8d4af025179-1.gif\" alt=\"\" class=\"wp-image-3248\" \/><\/noscript><figcaption>Fahrsch\u00fcler \u00dcbersicht <br>Quelle: ClickClickDrive<\/figcaption><\/figure>\n\n\n\n<h4 class=\"has-text-align-center wp-block-heading\">Herbst-Update<\/h4>\n\n\n\n<p>Wie Sie bekanntlich wissen stellen T\u00dcV\/Dekra zum 01.10.2021 einen neuen Pr\u00fcfungskatalog bereit, welcher in unserer App aktualisiert wird.&nbsp;<\/p>\n\n\n\n<p>Wie gewohnt entwickeln wir auf der Basis Ihrer Feedbacks unsere L\u00f6sungen f\u00fcr Sie weiter.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Eine neue, benutzerfreundlichere Statistik mit neuen Filterkriterien.<\/li><li>Sch\u00fcler und Sch\u00fclerinnen werden die M\u00f6glichkeit bekommen sich online in Ihrer Fahrschule zur F\u00fchrerscheinausbildung an zu melden.<\/li><\/ul>\n\n\n\n<p>Wir sind auch \u00fcber jedes Feedback Ihrerseits stets dankbar und&nbsp;aufgeschlossen. Sollte Sie also ein Feedback f\u00fcr uns parat haben oder haben Sie anderweitig Fragen zu uns oder unseren Produkten, dann k\u00f6nnen Sie jederzeit auf uns zu kommen.<\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-b287059c-2642-4748-b2ac-7abc37c6e66a\"><li>Per Telefon: +49 3056 837 631 von 09:00 bis 18:00 Uhr<\/li><li>Per E-Mail: <a href=\"mailto:info@clickclickdrive.net\">info@clickclickdrive.net<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Was erwartet Sie diesen Monat neues bei ClickClickDrive? Das fassen wir Ihnen in dieser Mail einmal kurz und b\u00fcndig zusammen. Zeitraum: September 2021 Produkt: Verwaltungssoftware Bereich: Theorie Zum Einen gibt es ein neue \u00fcberarbeitete Ansicht&nbsp;Ihrer f\u00fcr die Theorie-App registrierten Sch\u00fcler und Sch\u00fclerinnen:&nbsp;Dort k\u00f6nnen Sie&nbsp;nun einsehen&nbsp;wann Sie Ihre&nbsp;Sch\u00fcler\/ die Sch\u00fclerin registriert haben, wann der erste Login stattgefunden hat und wann Sie den Zugang zur Theorie-App verl\u00e4ngert haben. Was gibt es sonst neues? Abgesehen davon erwarten Sie noch weitere Erweiterungen&nbsp;in der Software. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":3305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[258],"tags":[281,180,91,280,107,282,179],"class_list":["post-3245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artikel","tag-ccd","tag-clickclickdrive","tag-fahrschule","tag-fahrschule-gruenden","tag-fahrschueler","tag-fahrschulinhaber","tag-fahrschulverwaltungssoftware"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/posts\/3245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/comments?post=3245"}],"version-history":[{"count":5,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/posts\/3245\/revisions"}],"predecessor-version":[{"id":3289,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/posts\/3245\/revisions\/3289"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/media\/3305"}],"wp:attachment":[{"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/media?parent=3245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/categories?post=3245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.clickclickdrive.de\/blog\/wp-json\/wp\/v2\/tags?post=3245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}